{"id":51730,"date":"2023-04-19T10:55:45","date_gmt":"2023-04-19T07:55:45","guid":{"rendered":"https:\/\/www.gpec.ro\/?page_id=51730"},"modified":"2026-03-30T19:21:07","modified_gmt":"2026-03-30T16:21:07","slug":"gpec-meetup-chisinau","status":"publish","type":"page","link":"https:\/\/www.gpec.ro\/en\/gpec-meetup-chisinau\/","title":{"rendered":"GPeC Meetup Chi\u0219in\u0103u, March 19"},"content":{"rendered":"<div id=\"pl-51730\"  class=\"panel-layout\" ><div id=\"pg-51730-0\"  class=\"panel-grid panel-has-style\" ><div class=\"attending siteorigin-panels-stretch panel-row-style panel-row-style-for-51730-0\" data-stretch-type=\"full\" ><div id=\"pgc-51730-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-0-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"col-full panel-widget-style panel-widget-style-for-51730-0-0-0\" id=\"speaker\" ><div id=\"pl-w69b038ef34162\"  class=\"panel-layout\" ><div id=\"pg-w69b038ef34162-0\"  class=\"panel-grid panel-has-style\" ><div class=\"center-title panel-row-style panel-row-style-for-w69b038ef34162-0\" ><div id=\"pgc-w69b038ef34162-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b038ef34162-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"element-title title-centre-p panel-widget-style panel-widget-style-for-w69b038ef34162-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Learn from some of the best specialists<\/h3>\n<h2 style=\"text-align: center;\">Everything that matters in E-Commerce &amp; Online Marketing in 2026<\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-w69b038ef34162-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69b038ef34162-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b038ef34162-1-0-0\" class=\"so-panel widget widget_siteorigin-panels-postloop panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"row event-speakers-loop no-pagination panel-widget-style panel-widget-style-for-w69b038ef34162-1-0-0\" ><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/ioana-anescu-2\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"1099\" height=\"1098\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo.jpg 1099w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo-1024x1024.jpg 1024w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo-768x767.jpg 768w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Ioana-Anescu-Profile-Photo-100x100.jpg 100w\" sizes=\"auto, (max-width: 1099px) 100vw, 1099px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Growth Marketing Manager, GPeC<\/p>\n        <p class=\"speakerNume\">Ioana Anescu<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/liliana-busuioc\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/06\/liliana-busuioc.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/06\/liliana-busuioc.jpg 500w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/06\/liliana-busuioc-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/06\/liliana-busuioc-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/06\/liliana-busuioc-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/06\/liliana-busuioc-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/06\/liliana-busuioc-100x100.jpg 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Director Executiv AIM Moldova<\/p>\n        <p class=\"speakerNume\">Liliana Busuioc<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/sergiu-sobuleac\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2543\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-scaled.jpg 2560w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-300x298.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-1024x1017.jpg 1024w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-768x763.jpg 768w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-1536x1526.jpg 1536w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-2048x2035.jpg 2048w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-416x413.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/RS0_1422-100x100.jpg 100w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">CEO iute Moldova<\/p>\n        <p class=\"speakerNume\">Sergiu Sobuleac<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/igor-strechi\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"613\" height=\"613\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Igor-Strechi-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Igor-Strechi-1.jpg 613w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Igor-Strechi-1-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Igor-Strechi-1-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Igor-Strechi-1-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Igor-Strechi-1-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Igor-Strechi-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">CTO Purple Media<\/p>\n        <p class=\"speakerNume\">Igor Strechi<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/irina-tolstousov\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-scaled.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-scaled.jpg 2560w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-1024x1024.jpg 1024w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-768x768.jpg 768w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-1536x1536.jpg 1536w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-2048x2048.jpg 2048w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/AI-28-100x100.jpg 100w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Deputy Director, Invest Moldova Agency<\/p>\n        <p class=\"speakerNume\">Irina Tolstousov<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/lucian-pantece\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"959\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/01\/Lucian-Pantece-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/01\/Lucian-Pantece-1.jpg 950w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/01\/Lucian-Pantece-1-297x300.jpg 297w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/01\/Lucian-Pantece-1-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/01\/Lucian-Pantece-1-768x775.jpg 768w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/01\/Lucian-Pantece-1-416x420.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/01\/Lucian-Pantece-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Marketplace Operations Director eMAG<\/p>\n        <p class=\"speakerNume\">Lucian P\u00e2ntece<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/carolina-parcalab\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"964\" height=\"971\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Carolina-Parcalab-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Carolina-Parcalab-1.jpg 964w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Carolina-Parcalab-1-298x300.jpg 298w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Carolina-Parcalab-1-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Carolina-Parcalab-1-768x774.jpg 768w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Carolina-Parcalab-1-416x419.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Carolina-Parcalab-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 964px) 100vw, 964px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Legal Manager at ACI Partners<\/p>\n        <p class=\"speakerNume\">Carolina P\u00e2rc\u0103lab<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/mila-tomsa\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"904\" height=\"942\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/mila.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/mila.jpeg 904w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/mila-288x300.jpeg 288w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/mila-768x800.jpeg 768w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/mila-416x433.jpeg 416w\" sizes=\"auto, (max-width: 904px) 100vw, 904px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Mila Tom\u015fa, co-fondator, Pearl Code<\/p>\n        <p class=\"speakerNume\">Mila Tom\u015fa<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/georgeta-mir\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"659\" height=\"688\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Georgeta-Mir.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Georgeta-Mir.jpg 659w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Georgeta-Mir-287x300.jpg 287w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/03\/Georgeta-Mir-416x434.jpg 416w\" sizes=\"auto, (max-width: 659px) 100vw, 659px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Fondatoare &amp; designer, Georgette<\/p>\n        <p class=\"speakerNume\">Georgeta Mir <\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/veronica-sireteanu\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"1054\" height=\"1099\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Veronica-Sireteanu-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Veronica-Sireteanu-1.jpg 1054w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Veronica-Sireteanu-1-288x300.jpg 288w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Veronica-Sireteanu-1-982x1024.jpg 982w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Veronica-Sireteanu-1-768x801.jpg 768w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2026\/02\/Veronica-Sireteanu-1-416x434.jpg 416w\" sizes=\"auto, (max-width: 1054px) 100vw, 1054px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Deputy Director on Advocacy &amp; Business Development, AmCham Moldova<\/p>\n        <p class=\"speakerNume\">Veronica Sire\u021beanu<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/george-raschitor\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/George-Raschitor.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/George-Raschitor.jpg 450w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/George-Raschitor-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/George-Raschitor-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/George-Raschitor-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/George-Raschitor-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/George-Raschitor-100x100.jpg 100w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">General Manager | SINAPS Marketing<\/p>\n        <p class=\"speakerNume\">George R\u0103\u0219chitor<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/felicia-jereghi\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"460\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Felicia-Jereghi.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Felicia-Jereghi.jpg 460w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Felicia-Jereghi-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Felicia-Jereghi-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Felicia-Jereghi-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Felicia-Jereghi-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/06\/Felicia-Jereghi-100x100.jpg 100w\" sizes=\"auto, (max-width: 460px) 100vw, 460px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Managing Director - Indigo Grup | CEO - Hive5.digital  <\/p>\n        <p class=\"speakerNume\">Felicia Jereghi<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/andrei-radu\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/01\/Andrei-Radu-CEO_Founder-GPeC.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/01\/Andrei-Radu-CEO_Founder-GPeC.jpg 500w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/01\/Andrei-Radu-CEO_Founder-GPeC-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/01\/Andrei-Radu-CEO_Founder-GPeC-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/01\/Andrei-Radu-CEO_Founder-GPeC-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/01\/Andrei-Radu-CEO_Founder-GPeC-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/01\/Andrei-Radu-CEO_Founder-GPeC-100x100.jpg 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">CEO &amp; Founder GPeC<\/p>\n        <p class=\"speakerNume\">Andrei Radu<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/cornel-morcov\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/07\/Cornel-Morcov-FAN-Courier_speaker_GPeC.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Cornel Morcov FAN Courier speaker GPeC\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/07\/Cornel-Morcov-FAN-Courier_speaker_GPeC.jpg 500w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/07\/Cornel-Morcov-FAN-Courier_speaker_GPeC-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/07\/Cornel-Morcov-FAN-Courier_speaker_GPeC-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/07\/Cornel-Morcov-FAN-Courier_speaker_GPeC-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/07\/Cornel-Morcov-FAN-Courier_speaker_GPeC-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/07\/Cornel-Morcov-FAN-Courier_speaker_GPeC-100x100.jpg 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Chief Commercial Officer FAN Courier<\/p>\n        <p class=\"speakerNume\">Cornel Morcov<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/bogdan-manolea\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/03\/Bogdan-Manolea-TRUSTED-GPeC.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Bogdan Manolea Co-Founder TRUSTED.ro Scoala de Vara de E-Commerce GPeC\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/03\/Bogdan-Manolea-TRUSTED-GPeC.png 512w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/03\/Bogdan-Manolea-TRUSTED-GPeC-300x300.png 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/03\/Bogdan-Manolea-TRUSTED-GPeC-150x150.png 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/03\/Bogdan-Manolea-TRUSTED-GPeC-324x324.png 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/03\/Bogdan-Manolea-TRUSTED-GPeC-416x416.png 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/03\/Bogdan-Manolea-TRUSTED-GPeC-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Co-Founder TRUSTED.ro &amp; Director Executiv APTI<\/p>\n        <p class=\"speakerNume\">Bogdan Manolea<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><div class=\"col-xl-3 col-md-12\">\n  <a href=\"https:\/\/www.gpec.ro\/en\/speakeri\/mihai-vinatoru\/\">\n    <div class=\"speakerBox\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Mihai-Vinatoru.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Mihai V\u00een\u0103toru DWF trainer \u0218coala de Var\u0103 GPeC\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Mihai-Vinatoru.jpg 800w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Mihai-Vinatoru-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Mihai-Vinatoru-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Mihai-Vinatoru-768x768.jpg 768w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Mihai-Vinatoru-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Mihai-Vinatoru-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Mihai-Vinatoru-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>      <div class=\"speakerContent\">\n        <p class=\"speakerFunctie\">Managing Partner DWF<\/p>\n        <p class=\"speakerNume\">Mihai V\u00een\u0103toru<\/p>\n      <\/div>\n    <\/div>\n  <\/a>\t\t\t\t\t\t\t\t\t\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w69b038ef34162-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69b038ef34162-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b038ef34162-2-0-0\" class=\"so-panel widget widget_sow-button panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-flat-a7e34ebbd997\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-center\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"#sign-up\"\n\t\t\t\t\tclass=\"main-btn sowb-button ow-icon-placement-left ow-button-hover\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tRegister for GPeC Meetup Chi\u0219in\u0103u, March 19\t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-51730-1\"  class=\"panel-grid panel-has-style\" ><div class=\"attending siteorigin-panels-stretch panel-row-style panel-row-style-for-51730-1\" data-stretch-type=\"full\" ><div id=\"pgc-51730-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-1-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child\" data-index=\"1\" ><div class=\"col-full panel-widget-style panel-widget-style-for-51730-1-0-0\" ><div id=\"pl-w699fe9835a65e\"  class=\"panel-layout\" ><div id=\"pg-w699fe9835a65e-0\"  class=\"panel-grid panel-has-style\" ><div class=\"gold e-counter panel-row-style panel-row-style-for-w699fe9835a65e-0\" ><div id=\"pgc-w699fe9835a65e-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w699fe9835a65e-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"element-counter panel-widget-style panel-widget-style-for-w699fe9835a65e-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3>1<\/h3>\n<h2>exclusive day<\/h2>\n<p>with limited places<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-w699fe9835a65e-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w699fe9835a65e-0-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"element-counter panel-widget-style panel-widget-style-for-w699fe9835a65e-0-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3>10+<\/h3>\n<h2>top notch<\/h2>\n<p>speakers<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-w699fe9835a65e-0-2\"  class=\"panel-grid-cell\" ><div id=\"panel-w699fe9835a65e-0-2-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" ><div class=\"element-counter panel-widget-style panel-widget-style-for-w699fe9835a65e-0-2-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3>8<\/h3>\n<h2>hours<\/h2>\n<p>of practical content<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-w699fe9835a65e-0-3\"  class=\"panel-grid-cell\" ><div id=\"panel-w699fe9835a65e-0-3-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"3\" ><div class=\"element-counter panel-widget-style panel-widget-style-for-w699fe9835a65e-0-3-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3>100%<\/h3>\n<h2>networking<\/h2>\n<p>with the digital elite<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"panel-51730-1-0-1\" class=\"so-panel widget widget_sow-button panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-flat-a7e34ebbd997-24708\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-center\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"#sign-up\"\n\t\t\t\t\tclass=\"main-btn sowb-button ow-icon-placement-left ow-button-hover\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tRegister for GPeC Meetup Chi\u0219in\u0103u March 19 \t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-51730-2\"  class=\"panel-grid panel-has-style\" ><div class=\"attending siteorigin-panels-stretch panel-row-style panel-row-style-for-51730-2\" data-stretch-type=\"full\" ><div id=\"pgc-51730-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-2-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"3\" ><div class=\"col-full panel-widget-style panel-widget-style-for-51730-2-0-0\" id=\"what-you-expect\" ><div id=\"pl-w69b038ef38100\"  class=\"panel-layout\" ><div id=\"pg-w69b038ef38100-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69b038ef38100-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b038ef38100-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"element-title panel-widget-style panel-widget-style-for-w69b038ef38100-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3>E-Commerce, Digital Marketing &amp; Exclusive Networking<\/h3>\n<h2>What awaits you at GPeC Meetup, March 19, Chi\u0219in\u0103u<\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w69b038ef38100-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69b038ef38100-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b038ef38100-1-0-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"1\" ><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"427\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/09\/GPeC-SUMMIT-Audienta.jpg\" class=\"image wp-image-26684  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/09\/GPeC-SUMMIT-Audienta.jpg 550w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/09\/GPeC-SUMMIT-Audienta-300x233.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/09\/GPeC-SUMMIT-Audienta-416x323.jpg 416w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/div><\/div><div id=\"pgc-w69b038ef38100-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b038ef38100-1-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" ><div class=\"element-title panel-widget-style panel-widget-style-for-w69b038ef38100-1-1-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<div class=\"flex flex-col text-sm pb-25\">\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"9204746d-9e2b-4c81-9999-e7790cbe7d50\" data-testid=\"conversation-turn-2\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"bf5ea6bc-4cba-4361-9c97-7eeb825bce25\" data-message-model-slug=\"gpt-5-2\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word dark markdown-new-styling\">\n<ul>\n<li data-start=\"0\" data-end=\"94\">1 full day of practical insights on how to sell and do online marketing with results in 2026<\/li>\n<li data-start=\"96\" data-end=\"187\">10+ E-Commerce and Digital Marketing specialists from Romania and the Republic of Moldova<\/li>\n<li data-start=\"189\" data-end=\"268\">An exclusive, limited-seat event designed to facilitate high-level networking<\/li>\n<li data-start=\"270\" data-end=\"410\">Opportunities for business expansion and growth alongside some of the best service providers \u2013 direct contact with C-level representatives<\/li>\n<li data-start=\"412\" data-end=\"531\">Keynotes and open dialogues where we call things by their name, no sugarcoating, and with plenty of concrete examples<\/li>\n<li data-start=\"533\" data-end=\"589\">Exclusive venue: Radisson Blu Leogrand Hotel, Chi\u0219in\u0103u<\/li>\n<li data-start=\"591\" data-end=\"656\">Coffee Breaks &amp; Lunch included, alongside speakers and organizers<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"pointer-events-none h-px w-px absolute bottom-0\" aria-hidden=\"true\" data-edge=\"true\"><\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w69b038ef38100-2\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-w69b038ef38100-2\" ><div id=\"pgc-w69b038ef38100-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b038ef38100-2-0-0\" class=\"so-panel widget widget_sow-button panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-flat-a7e34ebbd997\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-center\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"#sign-up\"\n\t\t\t\t\tclass=\"main-btn sowb-button ow-icon-placement-left ow-button-hover\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tSecure your place at GPeC Meetup Chi\u0219in\u0103u\t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-51730-3\"  class=\"panel-grid panel-has-style\" ><div class=\"attending siteorigin-panels-stretch panel-row-style panel-row-style-for-51730-3\" data-stretch-type=\"full\" ><div id=\"pgc-51730-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-3-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"col-full panel-widget-style panel-widget-style-for-51730-3-0-0\" ><div id=\"pl-w699feb1ccad68\"  class=\"panel-layout\" ><div id=\"pg-w699feb1ccad68-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w699feb1ccad68-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w699feb1ccad68-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"element-title panel-widget-style panel-widget-style-for-w699feb1ccad68-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 class=\"eventDate\">Hot Topics<\/h3>\n<h2 data-start=\"0\" data-end=\"55\">What we\u2019ll cover at GPeC Meetup Chi\u0219in\u0103u \u2013 March 19<\/h2>\n<ul>\n<li data-start=\"59\" data-end=\"268\">The latest updates on the E-Commerce markets in Romania and the Republic of Moldova: newest figures, consumer behavior, top-selling product categories, AOV, challenges and growth opportunities, cross-border;<\/li>\n<li data-start=\"271\" data-end=\"370\">Digital Marketing in the AI era \u2013 how to leverage artificial intelligence in marketing campaigns;<\/li>\n<li data-start=\"373\" data-end=\"455\">How to automate repetitive processes with AI to increase business profitability;<\/li>\n<li data-start=\"458\" data-end=\"518\">How important branding becomes in a world dominated by AI;<\/li>\n<li data-start=\"521\" data-end=\"599\">Logistics and courier services: exporting to Romania and other EU countries;<\/li>\n<li data-start=\"602\" data-end=\"644\">Essential legal aspects for online stores.<\/li>\n<\/ul>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-w699feb1ccad68-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w699feb1ccad68-0-1-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"1\" ><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/chisinau-gpec-moldova-mobil-1.jpg\" class=\"image wp-image-56219  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/chisinau-gpec-moldova-mobil-1.jpg 500w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/chisinau-gpec-moldova-mobil-1-300x300.jpg 300w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/chisinau-gpec-moldova-mobil-1-150x150.jpg 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/chisinau-gpec-moldova-mobil-1-324x324.jpg 324w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/chisinau-gpec-moldova-mobil-1-416x416.jpg 416w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/chisinau-gpec-moldova-mobil-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-51730-4\"  class=\"panel-grid panel-has-style\" ><div class=\"attending siteorigin-panels-stretch panel-row-style panel-row-style-for-51730-4\" data-stretch-type=\"full\" ><div id=\"pgc-51730-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-4-0-0\" class=\"widget_text so-panel widget widget_custom_html panel-first-child\" data-index=\"5\" ><div class=\"widget_text element-title text-center panel-widget-style panel-widget-style-for-51730-4-0-0\" ><div class=\"textwidget custom-html-widget\"><h2>\n\tJoin the companies that consistently participate in GPeC events.\n<\/h2><\/div><\/div><\/div><div id=\"panel-51730-4-0-1\" class=\"so-panel widget widget_siteorigin-panels-postloop panel-last-child\" data-index=\"6\" >  <!-- SLIDER QUERY -->\n  <div class=\"old-participanti-slider\">          \n\n        \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/anapan.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/answear.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/aqua.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/austral.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/avon.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/BB.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/bitdefender.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/BRD.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/BT.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/carturesti.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/chicco.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/ciel.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/cocacola.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2021\/05\/cora-logo.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/deichman.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/dhl.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/dor.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/dpd.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/ecco.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/ejobs.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2022\/04\/eMAG-nou.jpg\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Logo-ENGIE.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/f64.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/FD.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/flanco.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/floria.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/frisbo1.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/fup.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Desktop_basic_BlueYellow.svg\" class=\"img-fluid mx-auto\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/gsk.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/04\/parteneri-gpec.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/hcs.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/hm.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/Hornbach.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/ikea.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/ing.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/innobyte.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/lafantana-e1663580114150.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/lcwaikiki.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/leroy.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/leumi.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/loreal.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/mediagalaxy.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/melimelo.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/michelin.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/miniprix.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/mobexpert.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/nestle.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/olx.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/otter.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/paralela45.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/pepsico.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/piatra.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/sephora.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/teilor.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/tremend.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/tudor.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/uipath.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/unilever.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/ursus.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/velpitar.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/yvesrocher.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n          \n              \n          <div class=\"slider-item text-center\">\n           <!-- <a href=\"\"> -->\n              <img decoding=\"async\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2020\/02\/zitec-e1648199421763.png\" class=\"img-fluid mx-auto\" loading=\"lazy\" \/>\n          <!--     <\/a> -->\n          <\/div>            \n\n      \n              \n  <\/div><\/div><\/div><\/div><\/div><div id=\"pg-51730-5\"  class=\"panel-grid panel-has-style\" ><div class=\"attending siteorigin-panels-stretch panel-row-style panel-row-style-for-51730-5\" data-stretch-type=\"full\" ><div id=\"pgc-51730-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-5-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child\" data-index=\"7\" ><div class=\"col-full panel-widget-style panel-widget-style-for-51730-5-0-0\" id=\"why-join\" ><div id=\"pl-w69a159e707dc4\"  class=\"panel-layout\" ><div id=\"pg-w69a159e707dc4-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69a159e707dc4-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69a159e707dc4-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"element-title panel-widget-style panel-widget-style-for-w69a159e707dc4-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<div class=\"flex flex-col text-sm pb-25\">\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"0f422d54-5938-432a-a207-8ec4f97f1b30\" data-testid=\"conversation-turn-6\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"e80be819-6b42-466c-b8e8-8c71618e8147\" data-message-model-slug=\"gpt-5-2\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word dark markdown-new-styling\">\n<h3 data-start=\"0\" data-end=\"85\">Why should you attend?<\/h3>\n<h2 data-start=\"0\" data-end=\"85\">7 reasons you can\u2019t miss GPeC Meetup Chi\u0219in\u0103u \u2013 March 19<\/h2>\n<ul>\n<li data-start=\"89\" data-end=\"183\">You get access to some of the best expert speakers from Romania and the Republic of Moldova;<\/li>\n<li data-start=\"186\" data-end=\"374\">You learn, get inspired, and leave with ideas you can apply immediately \u2013 discover how to overcome today\u2019s challenges and explore future perspectives in E-Commerce and Digital Marketing;<\/li>\n<li data-start=\"377\" data-end=\"502\">The content is designed to be truly valuable for the audience \u2013 at GPeC, you won\u2019t sit through boring promotional speeches;<\/li>\n<li data-start=\"505\" data-end=\"619\">You\u2019ll gain insights into both the Romanian and Moldovan markets and learn how to sell online in both countries;<\/li>\n<li data-start=\"622\" data-end=\"759\">You benefit from high-level networking in an exclusive, limited setting alongside C-Level representatives of leading service providers;<\/li>\n<li data-start=\"762\" data-end=\"837\">You\u2019ll discover how to sell and do online marketing successfully in 2026;<\/li>\n<li data-start=\"840\" data-end=\"1105\">You become part of the GPeC Community \u2013 the most important network dedicated to Digital professionals, where you gain access to valuable resources, practical advice, service recommendations, and the right connections for everything you need in your online business.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"pointer-events-none h-px w-px absolute bottom-0\" aria-hidden=\"true\" data-edge=\"true\"><\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-w69a159e707dc4-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w69a159e707dc4-0-1-0\" class=\"so-panel widget widget_media_image panel-first-child panel-last-child\" data-index=\"1\" ><img loading=\"lazy\" decoding=\"async\" width=\"453\" height=\"605\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/download-36.png\" class=\"image wp-image-56196  attachment-full size-full\" alt=\"\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/download-36.png 453w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/download-36-225x300.png 225w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2024\/02\/download-36-416x556.png 416w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"panel-51730-5-0-1\" class=\"so-panel widget widget_siteorigin-panels-builder panel-last-child\" data-index=\"8\" ><div id=\"pl-w69b038ef39881\"  class=\"panel-layout\" ><div id=\"pg-w69b038ef39881-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69b038ef39881-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b038ef39881-0-0-0\" class=\"so-panel widget widget_sow-button panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-flat-a7e34ebbd997\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-center\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"#sign-up\"\n\t\t\t\t\tclass=\"main-btn sowb-button ow-icon-placement-left ow-button-hover\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tRegister for GPeC Meetup Chi\u0219in\u0103u, March 19 \t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-51730-6\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-51730-6\" data-stretch-type=\"full\" ><div id=\"pgc-51730-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-6-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"9\" ><div class=\"col-full panel-widget-style panel-widget-style-for-51730-6-0-0\" id=\"location\" ><div id=\"pl-w69a159e7088f9\"  class=\"panel-layout\" ><div id=\"pg-w69a159e7088f9-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69a159e7088f9-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69a159e7088f9-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"element-title panel-widget-style panel-widget-style-for-w69a159e7088f9-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 data-start=\"0\" data-end=\"79\">Where does GPeC Meetup \u2013 March 19 take place?<\/h3>\n<h2 data-start=\"0\" data-end=\"79\">Radisson Blu Leogrand Hotel<\/h2>\n<p data-start=\"81\" data-end=\"195\" data-is-last-node=\"\" data-is-only-node=\"\">GPeC Meetup Chi\u0219in\u0103u \u2013 March 19 takes place in an exclusive setting at <a style=\"font-size: 16px;\" href=\"https:\/\/www.radissonhotels.com\/en-us\/hotels\/radisson-blu-chisinau-leogrand\" target=\"_blank\" rel=\"noopener\"><strong>Hotel Radisson Blu Leogrand Chi\u0219in\u0103u<\/strong><\/a><span style=\"font-size: 16px;\">, right in the center of the Capital City on <\/span><a style=\"font-size: 16px;\" href=\"https:\/\/www.google.com\/maps\/place\/Radisson+Blu+Leogrand+Hotel,+Chisinau\/@47.0240861,28.8365665,17.87z\/data=!4m9!3m8!1s0x40c97c60af53d4e3:0x3481914e94541a10!5m2!4m1!1i2!8m2!3d47.0243431!4d28.8367554!16s%2Fg%2F1tfcx9ng\" target=\"_blank\" rel=\"noopener\"><strong>Str. Mitropolit Varlaam nr. 77<\/strong><\/a><span style=\"font-size: 16px;\">.<\/span><\/p>\n<p>Due to the limited number of parking spaces in the area, we recommend <strong>using alternative transportation options instead of your personal car to get to the event.<\/strong><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-w69a159e7088f9-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w69a159e7088f9-0-1-0\" class=\"widget_text so-panel widget widget_custom_html panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"textwidget custom-html-widget\"><script type=\"text\/javascript\">\r\ndocument.addEventListener(\"DOMContentLoaded\", function(event) { \r\n\tjQuery( '#slider-pro-3-52410' ).sliderPro({\r\n\t\t\/\/width\r\n\t\t\t\twidth: \"100%\",\r\n\t\t\t\t\r\n\t\t\/\/height\r\n\t\t\t\theight: 330,\r\n\t\t\t\t\r\n\t\t\/\/auto play\r\n\t\t\t\t\t\t\t\tautoplay:  false,\r\n\t\t\t\tautoplayDelay: 5000,\r\n\t\t\r\n\t\t\r\n\t\tarrows: true,\r\n\t\tbuttons: false,\r\n\t\tsmallSize: 500,\r\n\t\tmediumSize: 1000,\r\n\t\tlargeSize: 3000,\r\n\t\tfade: true,\r\n\t\t\r\n\t\t\/\/thumbnail\r\n\t\tthumbnailArrows: true,\r\n\t\tthumbnailWidth: 100,\r\n\t\tthumbnailHeight: 90,\r\n\t\t\t\t\t\tthumbnailsPosition: 'bottom',\r\n\t\t\t\t\t\tthumbnailPointer: true, \r\n\t\t\t\tcenterImage: true,\r\n\t\timageScaleMode: 'cover',\r\n\t\tallowScaleUp: false,\r\n\t\t\t\tstartSlide: 0,\r\n\t\tloop: true,\r\n\t\tslideDistance: 5,\r\n\t\tautoplayDirection: 'normal',\r\n\t\ttouchSwipe: true,\r\n\t\tfullScreen: true,\r\n\t});\r\n});\r\n<\/script>\r\n\r\n\t\t<div id=\"slider-pro-3-52410\" class=\"slider-pro\">\r\n\t\t\t<!---- slides div start ---->\r\n\t\t\t<div class=\"sp-slides\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"sp-slide\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-image\" loading=\"lazy\" alt=\"16256-114116-f63763151_3xl\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/css\/images\/blank.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/16256-114116-f63763151_3xl.jpg\" \/>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sp-slide\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-image\" loading=\"lazy\" alt=\"16256-114116-f62737730_3xl (1)\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/css\/images\/blank.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/16256-114116-f62737730_3xl-1.jpg\" \/>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sp-slide\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-image\" loading=\"lazy\" alt=\"16256-114116-f62737714_3xl (1)\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/css\/images\/blank.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/16256-114116-f62737714_3xl-1.jpg\" \/>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sp-slide\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-image\" loading=\"lazy\" alt=\"16256-114116-f62737774_3xl\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/css\/images\/blank.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/16256-114116-f62737774_3xl.jpg\" \/>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sp-slide\">\r\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-image\" loading=\"lazy\" alt=\"download (2)\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/css\/images\/blank.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/download-2.png\" \/>\r\n\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t<!---- slides div end ---->\r\n\t\t\t\t\t\t<!-- slides thumbnails div start -->\r\n\t\t\t<div class=\"sp-thumbnails\">\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-thumbnail\" loading=\"lazy\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/img\/loading.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/16256-114116-f63763151_3xl-300x172.jpg\" alt=\"16256-114116-f63763151_3xl\"\/>\r\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-thumbnail\" loading=\"lazy\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/img\/loading.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/16256-114116-f62737730_3xl-1-300x270.jpg\" alt=\"16256-114116-f62737730_3xl (1)\"\/>\r\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-thumbnail\" loading=\"lazy\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/img\/loading.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/16256-114116-f62737714_3xl-1-300x229.jpg\" alt=\"16256-114116-f62737714_3xl (1)\"\/>\r\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-thumbnail\" loading=\"lazy\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/img\/loading.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/16256-114116-f62737774_3xl-300x172.jpg\" alt=\"16256-114116-f62737774_3xl\"\/>\r\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"sp-thumbnail\" loading=\"lazy\" src=\"https:\/\/www.gpec.ro\/wp-content\/plugins\/ultimate-responsive-image-slider\/assets\/img\/loading.gif\" data-src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2023\/05\/download-2-300x229.png\" alt=\"download (2)\"\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<!-- slides thumbnails div end -->\r\n\t\t<\/div>\r\n\t\t<style>\r\n\/* Layout 3 *\/\r\n\/* border *\/\r\n\r\n\/* font + color *\/\r\n.title-in  {\r\n\tfont-family: Arial !important;\r\n\tcolor: #FFFFFF !important;\r\n\tbackground-color: #ffffff !important;\r\n\topacity: 0.7 !important;\r\n}\r\n.desc-in  {\r\n\tfont-family: Arial !important;\r\n\tcolor: #FFFFFF !important;\r\n\tbackground-color: #00000 !important;\r\n\topacity: 0.7 !important;\r\n}\r\n\r\n\/* bullets color *\/\r\n.sp-button  {\r\n\tborder: 2px solid #000000 !important;\r\n}\r\n.sp-selected-button  {\r\n\tbackground-color: #000000 !important;\r\n}\r\n\r\n\/* pointer color - bottom *\/\r\n.sp-selected-thumbnail::before {\r\n\tborder-bottom: 5px solid #ffffff !important;\r\n}\r\n.sp-selected-thumbnail::after {\r\n\tborder-bottom: 13px solid #ffffff !important;\r\n}\r\n\r\n\/* pointer color - top *\/\r\n\r\n\/* full screen icon *\/\r\n.sp-full-screen-button::before {\r\n    color: #FFFFFF !important;\r\n}\r\n\r\n\/* hover navigation icon color *\/\r\n.sp-next-arrow::after, .sp-next-arrow::before {\r\n\tbackground-color: #FFFFFF !important;\r\n}\r\n.sp-previous-arrow::after, .sp-previous-arrow::before {\r\n\tbackground-color: #FFFFFF !important;\r\n}\r\n\r\n#slider-pro-3-52410 .title-in {\r\n\tcolor: #FFFFFF !important;\r\n\tfont-weight: bolder;\r\n\ttext-align: center;\r\n}\r\n\r\n#slider-pro-3-52410 .title-in-bg {\r\n\tbackground: rgba(255, 255, 255, 0.7); !important;\r\n\twhite-space: unset !important;\r\n\ttransform: initial !important;\r\n\t-webkit-transform: initial !important;\r\n\tfont-size: 14px !important;\r\n}\r\n\r\n#slider-pro-3-52410 .desc-in {\r\n\tcolor: #FFFFFF !important;\r\n\ttext-align: center;\r\n}\r\n#slider-pro-3-52410 .desc-in-bg {\r\n\tbackground: rgba(#00000, 0.7) !important;\r\n\twhite-space: unset !important;\r\n\ttransform: initial !important;\r\n\t-webkit-transform: initial !important;\r\n\tfont-size: 13px !important;\r\n}\r\n\r\n@media (max-width: 640px) {\r\n\t#slider-pro-3-52410 .hide-small-screen {\r\n\t\tdisplay: none;\r\n\t}\r\n}\r\n\r\n@media (max-width: 860px) {\r\n\t#slider-pro-3-52410 .sp-layer {\r\n\t\tfont-size: 18px;\r\n\t}\r\n\t\r\n\t#slider-pro-3-52410 .hide-medium-screen {\r\n\t\tdisplay: none;\r\n\t}\r\n}\r\n.slides-not-found {\r\n\tbackground-color: #a92929;\r\n\tborder-radius: 5px;\r\n\tcolor: #fff;\r\n\tfont-family: initial;\r\n\ttext-align: center;\r\n\tpadding:12px;\r\n}\r\n\/* Custom CSS *\/\r\n<\/style>\r\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-51730-7\"  class=\"panel-grid panel-has-style\" ><div class=\"attending panel-row-style panel-row-style-for-51730-7\" id=\"sign-up\" ><div id=\"pgc-51730-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-7-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"10\" ><div class=\"col-full bilete-noi bilete-summit-moldova panel-widget-style panel-widget-style-for-51730-7-0-0\" ><div id=\"pl-w69b1d0be29260\"  class=\"panel-layout\" ><div id=\"pg-w69b1d0be29260-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69b1d0be29260-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b1d0be29260-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"element-title  panel-widget-style panel-widget-style-for-w69b1d0be29260-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\">Tickets for GPeC Meetup Chi\u0219in\u0103u March 19, 2026<\/h2>\n<h4 style=\"text-align: center;\">Limited seats!<\/h4>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w69b1d0be29260-1\"  class=\"panel-grid panel-has-style\" ><div class=\"bilete-magazin bilete-summit bilete-titlu-bk panel-row-style panel-row-style-for-w69b1d0be29260-1\" ><div id=\"pgc-w69b1d0be29260-1-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><div class=\"bilet-single panel-cell-style panel-cell-style-for-w69b1d0be29260-1-0\" ><\/div><\/div><div id=\"pgc-w69b1d0be29260-1-1\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div class=\"bilet-single panel-cell-style panel-cell-style-for-w69b1d0be29260-1-1\" ><div id=\"panel-w69b1d0be29260-1-1-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"bilete vip-box panel-widget-style panel-widget-style-for-w69b1d0be29260-1-1-0\" ><div id=\"pl-w69b1d0be2926a\"  class=\"panel-layout\" ><div id=\"pg-w69b1d0be2926a-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69b1d0be2926a-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69b1d0be2926a-0-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child\" data-index=\"0\" ><div class=\"eticheta et-moldova panel-widget-style panel-widget-style-for-w69b1d0be2926a-0-0-0\" ><div id=\"pl-w699c5d37165d5\"  class=\"panel-layout\" ><div id=\"pg-w699c5d37165d5-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w699c5d37165d5-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w699c5d37165d5-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"corner sold-out panel-widget-style panel-widget-style-for-w699c5d37165d5-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-47475\" src=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2022\/05\/sold-out.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.gpec.ro\/wp-content\/uploads\/2022\/05\/sold-out.png 200w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2022\/05\/sold-out-150x150.png 150w, https:\/\/www.gpec.ro\/wp-content\/uploads\/2022\/05\/sold-out-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/strong><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"panel-w69b1d0be2926a-0-0-1\" class=\"so-panel widget widget_sow-editor\" data-index=\"1\" ><div class=\"data-bilete panel-widget-style panel-widget-style-for-w69b1d0be2926a-0-0-1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Attending ticket<\/span><br \/>\n<span style=\"color: #000000;\">March 19, 2026<\/span><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"panel-w69b1d0be2926a-0-0-2\" class=\"so-panel widget widget_sow-editor\" data-index=\"2\" ><div class=\"element-title pret-bilete panel-widget-style panel-widget-style-for-w69b1d0be2926a-0-0-2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\"><del>149<\/del><strong> 99\u20ac<em>\/pers.<br \/>\n<\/em><\/strong><\/span><\/h2>\n<p style=\"text-align: center;\"><span style=\"color: #cc99ff;\"><strong><span style=\"color: #000000;\">Price available until 17th of March<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #cc99ff;\"><strong><span style=\"color: #000000;\">Attention: limited seats available!<\/span><br \/>\n<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #cc99ff;\"><strong>\u00a0<\/strong><\/span><\/p>\n<p><!--\n\n\n<\/p>\n\n\n\n<p style=\"text-align: center;\">OFERT\u0102 VERY EARLY BIRD<\/p>\n\n\n\n\n<span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span>\n\n\n\n\n<p style=\"text-align: center;\">VALABIL\u0102 P\u00c2N\u0102 PE <strong>7 APRILIE, ORA 23:59<\/strong><\/p>\n\n\n\n\n--><\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"panel-w69b1d0be2926a-0-0-3\" class=\"so-panel widget widget_siteorigin-panels-builder panel-last-child\" data-index=\"3\" ><div class=\"panel-widget-style panel-widget-style-for-w69b1d0be2926a-0-0-3\" ><div id=\"pl-w69a5a9499f75e\"  class=\"panel-layout\" ><div id=\"pg-w69a5a9499f75e-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69a5a9499f75e-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w69a5a9499f75e-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"0\" ><div class=\"element-title detalii-bilete panel-widget-style panel-widget-style-for-w69a5a9499f75e-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Attending ticket<\/h3>\n<\/div>\n<\/div><\/div><\/div><div id=\"panel-w69a5a9499f75e-0-0-1\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"1\" ><div class=\"element-title detalii-bilete panel-widget-style panel-widget-style-for-w69a5a9499f75e-0-0-1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<ul>\n<li data-start=\"2\" data-end=\"78\">Access to GPeC Meetup \u2013 March 19, 2026, at the Radisson Blu Leogrand Hotel<\/li>\n<li data-start=\"81\" data-end=\"191\">Access to the speakers\u2019 PowerPoint presentations from GPeC Meetup (where redistribution approval is granted)<\/li>\n<li data-start=\"194\" data-end=\"256\">Live Q&amp;A sessions with the speakers on the GPeC Meetup stage<\/li>\n<li data-start=\"259\" data-end=\"291\">Business opportunities &amp; leads<\/li>\n<li data-start=\"294\" data-end=\"366\">High-level networking with C-Level representatives attending the event<\/li>\n<li data-start=\"369\" data-end=\"419\">Coffee Breaks (coffee\/tea, snacks, refreshments)<\/li>\n<li data-start=\"422\" data-end=\"503\">Lunch &amp; Networking alongside GPeC Meetup speakers, organizers, and participants<\/li>\n<li data-start=\"506\" data-end=\"546\">Access to the professional photo archive<\/li>\n<\/ul>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w69a5a9499f75e-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w69a5a9499f75e-1-0\"  class=\"panel-grid-cell\" ><div class=\"panel-cell-style panel-cell-style-for-w69a5a9499f75e-1-0\" ><div id=\"panel-w69a5a9499f75e-1-0-0\" class=\"so-panel widget widget_sow-button panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-flat-d4faab13ab26\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-right\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/oveit.com\/hub\/event\/gpec-meetup-chisinau-19-martie-RzK5eWnN\"\n\t\t\t\t\tclass=\"main-btn sowb-button ow-icon-placement-left ow-button-hover\" target=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tAre you form Rom\u00e2nia \/ European Union? Register here!\t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pgc-w69a5a9499f75e-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-w69a5a9499f75e-1-1-0\" class=\"so-panel widget widget_sow-button panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-button so-widget-sow-button-flat-3e434930822d\"\n\t\t\t\n\t\t><div class=\"ow-button-base ow-button-align-left\"\n>\n\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/unde.io\/ro\/events\/1654-gpec-meetup-chisinau-19-martie#buyTickets\"\n\t\t\t\t\tclass=\"main-btn sowb-button ow-icon-placement-left ow-button-hover\" target=\"_blank\" rel=\"noopener noreferrer\" \t>\n\t\t<span>\n\t\t\t\n\t\t\tAre you from the Republic of Moldova? Register here!\t\t<\/span>\n\t\t\t<\/a>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pgc-w69b1d0be29260-1-2\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><div class=\"bilet-single panel-cell-style panel-cell-style-for-w69b1d0be29260-1-2\" ><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-51730-8\"  class=\"panel-grid panel-has-style\" ><div class=\"attending siteorigin-panels-stretch panel-row-style panel-row-style-for-51730-8\" data-stretch-type=\"full\" ><div id=\"pgc-51730-8-0\"  class=\"panel-grid-cell\" ><div id=\"panel-51730-8-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"11\" ><div class=\"col-full panel-widget-style panel-widget-style-for-51730-8-0-0\" id=\"testimoniale\" ><div id=\"pl-w699eb8bbda16f\"  class=\"panel-layout\" ><div id=\"pg-w699eb8bbda16f-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w699eb8bbda16f-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w699eb8bbda16f-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"element-title panel-widget-style panel-widget-style-for-w699eb8bbda16f-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\">Ce spun prietenii care au participat la evenimentele GPeC<\/h2>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w699eb8bbda16f-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w699eb8bbda16f-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w699eb8bbda16f-1-0-0\" class=\"so-panel widget widget_sow-testimonials panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-testimonials so-widget-sow-testimonials-default-be3490093031\"\n\t\t\t\n\t\t><div class=\"sow-testimonials\">\n\t\t\t\t\t<div class=\"sow-testimonial-wrapper sow-user-left sow-layout-text-above\">\n\t\t\t<div class=\"sow-testimonial\">\n\t\t\t\t\t\t\t\t\t<div class=\"sow-testimonial-text\">\n\t\t\t\t\t\t<blockquote>\n<p><em>It\u2019s THE PLACE to be if you want to learn what\u2019s top and newest in e-commerce! Captivating atmosphere, amazing, friendly and very professional staff team, inspiring speakers, endless networking resources! <\/em><\/p>\n<\/blockquote>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"sow-testimonial-user\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"sow-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sow-testimonial-name\"><strong>Ioana Rill<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-testimonial-wrapper sow-user-left sow-layout-text-above\">\n\t\t\t<div class=\"sow-testimonial\">\n\t\t\t\t\t\t\t\t\t<div class=\"sow-testimonial-text\">\n\t\t\t\t\t\t<blockquote>\n<p><em>O oportunitate real\u0103 de a fi la curent cu nout\u0103\u021bile din acest segment, tendin\u021be, solu\u021bii \u00een func\u021bie de nevoi, studii de caz\u2026 O surs\u0103 de informa\u021bie calitativ\u0103 \u0219i cum e \u0219i targetat\u0103, nu poate dec\u00e2t s\u0103 m\u0103 bucure. Succes!<\/em><\/p>\n<\/blockquote>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"sow-testimonial-user\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"sow-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sow-testimonial-name\"><strong>Simona Dediu<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-testimonial-wrapper sow-user-left sow-layout-text-above\">\n\t\t\t<div class=\"sow-testimonial\">\n\t\t\t\t\t\t\t\t\t<div class=\"sow-testimonial-text\">\n\t\t\t\t\t\t<blockquote>\n<p><em>Congrats for a great event with useful content for online money-makers!<\/em><\/p>\n<\/blockquote>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"sow-testimonial-user\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"sow-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sow-testimonial-name\"><strong>Monica Jitariuc<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-testimonial-wrapper sow-user-left sow-layout-text-above\">\n\t\t\t<div class=\"sow-testimonial\">\n\t\t\t\t\t\t\t\t\t<div class=\"sow-testimonial-text\">\n\t\t\t\t\t\t<blockquote>\n<p><em>Good opportunity to find out the things you didn\u2019t know about your business!<\/em><\/p>\n<\/blockquote>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"sow-testimonial-user\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"sow-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sow-testimonial-name\"><strong>Iulia M\u0103rg\u0103rit-Ivan<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-testimonial-wrapper sow-user-left sow-layout-text-above\">\n\t\t\t<div class=\"sow-testimonial\">\n\t\t\t\t\t\t\t\t\t<div class=\"sow-testimonial-text\">\n\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"vc_col-sm-9 wpb_column vc_column_container \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<blockquote>\n<p><em>Un eveniment interna\u021bional realizat ca la carte la care e musai s\u0103 participi dac\u0103 ai tangen\u021be cu online-ul, fie ca antreprenor, fie ca angajat sau freelancer. Recomand cu c\u0103ldur\u0103!<\/em><\/p>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"sow-testimonial-user\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"sow-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sow-testimonial-name\"><strong>Iulian Acatrinei<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"sow-testimonial-wrapper sow-user-left sow-layout-text-above\">\n\t\t\t<div class=\"sow-testimonial\">\n\t\t\t\t\t\t\t\t\t<div class=\"sow-testimonial-text\">\n\t\t\t\t\t\t<blockquote>\n<p><em>Dac\u0103 e\u0219ti online cu afacerea, indiferent de domeniul t\u0103u de activitate, sigur nu vrei s\u0103 ratezi un astfel de eveniment. Best e-commerce &amp; digital marketing event in Eastern Europe!<br \/>\n<\/em><\/p>\n<\/blockquote>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"sow-testimonial-user\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"sow-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sow-testimonial-name\"><strong>George Petrea<\/strong><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Learn from some of the best specialists Everything that matters in E-Commerce &amp; Online Marketing in 2026 Mila Tom\u015fa, co-fondator, Pearl Code Mila Tom\u015fa Fondatoare &amp; designer, Georgette Georgeta Mir CTO Purple Media Igor Strechi CEO iute Moldova Sergiu Sobuleac Deputy Director on Advocacy &amp; Business Development, AmCham Moldova Veronica Sire\u021beanu Legal Manager at ACI [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"single-eveniment-moldova.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-51730","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gpec.ro\/en\/wp-json\/wp\/v2\/pages\/51730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gpec.ro\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gpec.ro\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gpec.ro\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gpec.ro\/en\/wp-json\/wp\/v2\/comments?post=51730"}],"version-history":[{"count":35,"href":"https:\/\/www.gpec.ro\/en\/wp-json\/wp\/v2\/pages\/51730\/revisions"}],"predecessor-version":[{"id":64190,"href":"https:\/\/www.gpec.ro\/en\/wp-json\/wp\/v2\/pages\/51730\/revisions\/64190"}],"wp:attachment":[{"href":"https:\/\/www.gpec.ro\/en\/wp-json\/wp\/v2\/media?parent=51730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}